{"id":24165,"date":"2024-04-05T11:05:24","date_gmt":"2024-04-05T09:05:24","guid":{"rendered":"https:\/\/dgeric.cultura.gov.it\/?p=24165"},"modified":"2024-04-05T11:13:31","modified_gmt":"2024-04-05T09:13:31","slug":"bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano","status":"publish","type":"post","link":"https:\/\/dgeric.cultura.gov.it\/en\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/","title":{"rendered":"Call for expressions of interest for the identification of 6 members of the board of directors and scientific advisor of the Italian Institute for the History of the Risorgimento"},"content":{"rendered":"<p class=\" translation-block\">The General Directorate for Education, Research and Cultural Institutes of the Ministry of Culture publishes the <strong>Call for the acquisition of expressions of interest<\/strong> for the identification of <strong>six members of the council director and scientific consultant of the Italian Institute for the History of the Risorgimento<\/strong>.<\/p>\n<p><a href=\"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-Pubblico-Consiglio-direttivo-Risorgimento.pdf\"><strong>Call\u00a0<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Allegato-A.doc\">Model A<\/a><\/p>\n<p><a href=\"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/allegato-1-1.docx\">Attachment 1<\/a><\/p>\n<p><a href=\"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/all-2-dichiarazione-sostitutiva-di-certificazione.docx\">Attachment 2<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La Direzione generale Educazione, ricerca e istituti culturali del Ministero della Cultura pubblica il Bando per l\u2019acquisizione di manifestazione di interesse per la formazione delle &#8230; <\/p>","protected":false},"author":1,"featured_media":24218,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,18,19,31,189],"tags":[],"class_list":["post-24165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-avvisi","category-in-evidenza","category-istituti","category-servizio-ii","category-tutti-articoli"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bando per manifestazione di interesse per l\u2019individuazione di\u00a06 componenti del consiglio direttivo e di consulenza scientifica dell\u2019Istituto per la storia del risorgimento italiano - Direzione Generale Educazione, ricerca e istituti culturali<\/title>\n<meta name=\"description\" content=\"Bando per manifestazione di interesse per 6 componenti del consiglio direttivo dell\u2019Istituto per la storia del risorgimento italiano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dgeric.cultura.gov.it\/en\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando per manifestazione di interesse per l\u2019individuazione di\u00a06 componenti del consiglio direttivo e di consulenza scientifica dell\u2019Istituto per la storia del risorgimento italiano - Direzione Generale Educazione, ricerca e istituti culturali\" \/>\n<meta property=\"og:description\" content=\"Bando per manifestazione di interesse per 6 componenti del consiglio direttivo dell\u2019Istituto per la storia del risorgimento italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dgeric.cultura.gov.it\/en\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Direzione Generale Educazione, ricerca e istituti culturali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dger.web\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T09:05:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-05T09:13:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-consiglio-direttivo-Istituto-per-la-storia-del-risorgimento-italiano.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3396\" \/>\n\t<meta property=\"og:image:height\" content=\"1442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/\",\"url\":\"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/\",\"name\":\"Bando per manifestazione di interesse per l\u2019individuazione di\u00a06 componenti del consiglio direttivo e di consulenza scientifica dell\u2019Istituto per la storia del risorgimento italiano - Direzione Generale Educazione, ricerca e istituti culturali\",\"isPartOf\":{\"@id\":\"https:\/\/dgeric.cultura.gov.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-consiglio-direttivo-Istituto-per-la-storia-del-risorgimento-italiano.png\",\"datePublished\":\"2024-04-05T09:05:24+00:00\",\"dateModified\":\"2024-04-05T09:13:31+00:00\",\"author\":{\"@id\":\"https:\/\/dgeric.cultura.gov.it\/#\/schema\/person\/3e34c1de5522b9b23d7191788dea88df\"},\"description\":\"Bando per manifestazione di interesse per 6 componenti del consiglio direttivo dell\u2019Istituto per la storia del risorgimento italiano.\",\"breadcrumb\":{\"@id\":\"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#primaryimage\",\"url\":\"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-consiglio-direttivo-Istituto-per-la-storia-del-risorgimento-italiano.png\",\"contentUrl\":\"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-consiglio-direttivo-Istituto-per-la-storia-del-risorgimento-italiano.png\",\"width\":3396,\"height\":1442,\"caption\":\"Avviso consiglio direttivo Istituto per la storia del risorgimento italiano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dgeric.cultura.gov.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando per manifestazione di interesse per l\u2019individuazione di\u00a06 componenti del consiglio direttivo e di consulenza scientifica dell\u2019Istituto per la storia del risorgimento italiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dgeric.cultura.gov.it\/#website\",\"url\":\"https:\/\/dgeric.cultura.gov.it\/\",\"name\":\"Direzione Generale Educazione, ricerca e istituti culturali\",\"description\":\"Il nuovo sito web della Direzione generale Educazione, ricerca e istituti culturali del Ministero della cultura\",\"alternateName\":\"dgeric\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dgeric.cultura.gov.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dgeric.cultura.gov.it\/#\/schema\/person\/3e34c1de5522b9b23d7191788dea88df\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/dgeric.cultura.gov.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/73ce2d0d8c284cac6a168ef6fc4c913c1ecb8094b478747cc9378e8b01051435?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/73ce2d0d8c284cac6a168ef6fc4c913c1ecb8094b478747cc9378e8b01051435?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/dgeric.cultura.gov.it\"],\"url\":\"https:\/\/dgeric.cultura.gov.it\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando per manifestazione di interesse per l\u2019individuazione di\u00a06 componenti del consiglio direttivo e di consulenza scientifica dell\u2019Istituto per la storia del risorgimento italiano - Direzione Generale Educazione, ricerca e istituti culturali","description":"Bando per manifestazione di interesse per 6 componenti del consiglio direttivo dell\u2019Istituto per la storia del risorgimento italiano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dgeric.cultura.gov.it\/en\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/","og_locale":"en_GB","og_type":"article","og_title":"Bando per manifestazione di interesse per l\u2019individuazione di\u00a06 componenti del consiglio direttivo e di consulenza scientifica dell\u2019Istituto per la storia del risorgimento italiano - Direzione Generale Educazione, ricerca e istituti culturali","og_description":"Bando per manifestazione di interesse per 6 componenti del consiglio direttivo dell\u2019Istituto per la storia del risorgimento italiano.","og_url":"https:\/\/dgeric.cultura.gov.it\/en\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/","og_site_name":"Direzione Generale Educazione, ricerca e istituti culturali","article_publisher":"https:\/\/www.facebook.com\/dger.web","article_published_time":"2024-04-05T09:05:24+00:00","article_modified_time":"2024-04-05T09:13:31+00:00","og_image":[{"width":3396,"height":1442,"url":"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-consiglio-direttivo-Istituto-per-la-storia-del-risorgimento-italiano.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/","url":"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/","name":"Bando per manifestazione di interesse per l\u2019individuazione di\u00a06 componenti del consiglio direttivo e di consulenza scientifica dell\u2019Istituto per la storia del risorgimento italiano - Direzione Generale Educazione, ricerca e istituti culturali","isPartOf":{"@id":"https:\/\/dgeric.cultura.gov.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#primaryimage"},"image":{"@id":"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#primaryimage"},"thumbnailUrl":"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-consiglio-direttivo-Istituto-per-la-storia-del-risorgimento-italiano.png","datePublished":"2024-04-05T09:05:24+00:00","dateModified":"2024-04-05T09:13:31+00:00","author":{"@id":"https:\/\/dgeric.cultura.gov.it\/#\/schema\/person\/3e34c1de5522b9b23d7191788dea88df"},"description":"Bando per manifestazione di interesse per 6 componenti del consiglio direttivo dell\u2019Istituto per la storia del risorgimento italiano.","breadcrumb":{"@id":"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#primaryimage","url":"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-consiglio-direttivo-Istituto-per-la-storia-del-risorgimento-italiano.png","contentUrl":"https:\/\/dgeric.cultura.gov.it\/wp-content\/uploads\/2024\/04\/Avviso-consiglio-direttivo-Istituto-per-la-storia-del-risorgimento-italiano.png","width":3396,"height":1442,"caption":"Avviso consiglio direttivo Istituto per la storia del risorgimento italiano"},{"@type":"BreadcrumbList","@id":"https:\/\/dgeric.cultura.gov.it\/bando-per-manifestazione-di-interesse-per-6-componenti-del-consiglio-direttivo-dellistituto-per-la-storia-del-risorgimento-italiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dgeric.cultura.gov.it\/"},{"@type":"ListItem","position":2,"name":"Bando per manifestazione di interesse per l\u2019individuazione di\u00a06 componenti del consiglio direttivo e di consulenza scientifica dell\u2019Istituto per la storia del risorgimento italiano"}]},{"@type":"WebSite","@id":"https:\/\/dgeric.cultura.gov.it\/#website","url":"https:\/\/dgeric.cultura.gov.it\/","name":"Direzione Generale Educazione, ricerca e istituti culturali","description":"Il nuovo sito web della Direzione generale Educazione, ricerca e istituti culturali del Ministero della cultura","alternateName":"dgeric","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dgeric.cultura.gov.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/dgeric.cultura.gov.it\/#\/schema\/person\/3e34c1de5522b9b23d7191788dea88df","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dgeric.cultura.gov.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/73ce2d0d8c284cac6a168ef6fc4c913c1ecb8094b478747cc9378e8b01051435?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73ce2d0d8c284cac6a168ef6fc4c913c1ecb8094b478747cc9378e8b01051435?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/dgeric.cultura.gov.it"],"url":"https:\/\/dgeric.cultura.gov.it\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/24165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/comments?post=24165"}],"version-history":[{"count":6,"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/24165\/revisions"}],"predecessor-version":[{"id":24217,"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/24165\/revisions\/24217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/media\/24218"}],"wp:attachment":[{"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/media?parent=24165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/categories?post=24165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dgeric.cultura.gov.it\/en\/wp-json\/wp\/v2\/tags?post=24165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}